{"id":392,"date":"2017-12-15T03:56:41","date_gmt":"2017-12-15T03:56:41","guid":{"rendered":"https:\/\/woocommercecore.mystagingwebsite.com\/?product=belt"},"modified":"2019-02-05T15:25:29","modified_gmt":"2019-02-05T15:25:29","slug":"belt","status":"publish","type":"product","link":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/product\/belt\/","title":{"rendered":"Belt"},"content":{"rendered":"<p>Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is a simple product.<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/product\/belt\/\" title=\"Read More\"> <span class=\"button \">Read More<\/span><\/a><\/div>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[59],"product_tag":[],"class_list":["post-392","product","type-product","status-publish","product_cat-accessories","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/product\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/comments?post=392"}],"wp:attachment":[{"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/media?parent=392"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/product_brand?post=392"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/product_cat?post=392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/newsweek-pro\/news-it-pro\/wp-json\/wp\/v2\/product_tag?post=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}