{"id":148,"date":"2013-06-07T10:35:51","date_gmt":"2013-06-07T10:35:51","guid":{"rendered":"http:\/\/demo.woothemes.com\/woocommerce\/?post_type=product&amp;p=15"},"modified":"2013-06-07T10:35:51","modified_gmt":"2013-06-07T10:35:51","slug":"woo-logo","status":"publish","type":"product","link":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/product\/woo-logo\/","title":{"rendered":"Woo Logo"},"content":{"rendered":"<p>Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[19,24],"product_tag":[],"class_list":["post-148","product","type-product","status-publish","product_cat-clothing","product_cat-t-shirts","entry","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/product\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/comments?post=148"}],"wp:attachment":[{"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/product_brand?post=148"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/product_cat?post=148"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/demo.themeinprogress.eu\/tip-product-slider-pro\/wp-json\/wp\/v2\/product_tag?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}